{"id":4613,"date":"2022-01-13T05:41:46","date_gmt":"2022-01-13T05:41:46","guid":{"rendered":"https:\/\/laboratorioamare.com\/en\/?page_id=4613"},"modified":"2023-03-17T17:28:33","modified_gmt":"2023-03-17T17:28:33","slug":"acido-urico-en-orina-de-24-horas","status":"publish","type":"page","link":"https:\/\/laboratorioamare.com\/en\/estudios\/acido-urico-en-orina-de-24-horas\/","title":{"rendered":"\u00c1cido \u00darico en orina de 24 horas"},"content":{"rendered":"<p><section id=\"bt_bb_section6a04bf36b61e4\" class=\"bt_bb_section bt_bb_layout_wide bt_bb_vertical_align_top\"  data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_slider bt_bb_height_keep-height bt_bb_animation_fade animate\"><div class=\"slick-slider fade\"  data-slick='{ \"lazyLoad\": \"progressive\", \"cssEase\": \"ease-out\", \"speed\": \"300\", \"fade\": true, \"prevArrow\": \"&lt;button type=\\\"button\\\" class=\\\"slick-prev\\\" aria-label=\\\"Previous\\\" tabindex=\\\"0\\\" role=\\\"button\\\"&gt;&lt;\/button&gt;\", \"nextArrow\": \"&lt;button type=\\\"button\\\" class=\\\"slick-next\\\" aria-label=\\\"Next\\\" tabindex=\\\"0\\\" role=\\\"button\\\"&gt;&lt;\/button&gt;\", \"autoplay\": true, \"autoplaySpeed\": 5000}' ><div class=\"bt_bb_slider_item\" data-src-full=\"https:\/\/laboratorioamare.com\/en\/wp-content\/uploads\/2021\/12\/analisis-clinicos-laboratorioamare.png\"><img decoding=\"async\" src=\"https:\/\/laboratorioamare.com\/en\/wp-content\/uploads\/2021\/12\/analisis-clinicos-laboratorioamare.png\" alt=\"analisis-clinicos-laboratorioamare\"  title=\"analisis-clinicos-laboratorioamare\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a04bf36b8987\" class=\"bt_bb_section bt_bb_layout_boxed_1100 bt_bb_vertical_align_top\"  data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_medium\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><header class=\"bt_bb_headline bt_bb_font_weight_bold bt_bb_superheadline_font_weight_700 bt_bb_dash_none bt_bb_size_inherit bt_bb_align_center\" style=\";font-family:&#039;Barlow&#039;\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_center&quot;,&quot;def&quot;:&quot;center&quot;,&quot;xl&quot;:&quot;center&quot;}}\"><h1 style=\"font-family:'Barlow'; font-size:35px\" class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>\u00c1cido \u00darico en orina de 24 horas <\/span><\/span><\/h1><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_border_color_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_image bt_bb_shape_soft-rounded bt_bb_align_center bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_center&quot;,&quot;def&quot;:&quot;center&quot;,&quot;xl&quot;:&quot;center&quot;}}\"><span><img src = \"https:\/\/laboratorioamare.com\/en\/wp-content\/plugins\/bold-page-builder\/img\/blank.gif\" data-full_image_src=\"https:\/\/laboratorioamare.com\/en\/wp-content\/uploads\/2023\/03\/Imagen-3.png\" data-image_src=\"https:\/\/laboratorioamare.com\/en\/wp-content\/uploads\/2023\/03\/Imagen-3.png\" title=\"Imagen 3\" alt=\"https:\/\/laboratorioamare.com\/en\/wp-content\/uploads\/2023\/03\/Imagen-3.png\" class=\"btLazyLoadImage\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_center bt_bb_padding_normal bt_bb_animation_fade_in animate bt_bb_details-color_white\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_center&quot;,&quot;def&quot;:&quot;center&quot;,&quot;xl&quot;:&quot;center&quot;}}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_tabs bt_bb_color_scheme_3 bt_bb_style_simple bt_bb_shape_square\" style=\"; --tabs-primary-color:#33d1cb; --tabs-secondary-color:#191919;\" data-bt-override-class=\"{}\"><ul class=\"bt_bb_tabs_header\"><li><span>Descripci\u00f3n e indicaciones<\/span><\/li><\/ul><div class=\"bt_bb_tabs_tabs\"><div class=\"bt_bb_tab_item\">\r\n\t\t\t<div class=\"bt_bb_tab_content\"><div  class=\"bt_bb_text\" ><\/p>\n<p><span style=\"font-weight: 400\">Se recomienda no hacer ejercicio 24 horas antes de la toma de muestra. Siempre que sea posible el paciente deber\u00e1 suspender medicamentos 8 horas antes de la toma de la muestra. Evitar consumir bebidas alcoh\u00f3licas 24 horas antes de la toma de muestra. Si el paciente es mujer, que no se encuentre en su periodo menstrual.<\/span><\/p>\n<p>\n<\/div><\/div>\r\n\t\t<\/div><\/div><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_medium\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":3516,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-4613","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/pages\/4613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/comments?post=4613"}],"version-history":[{"count":2,"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/pages\/4613\/revisions"}],"predecessor-version":[{"id":5078,"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/pages\/4613\/revisions\/5078"}],"up":[{"embeddable":true,"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/pages\/3516"}],"wp:attachment":[{"href":"https:\/\/laboratorioamare.com\/en\/wp-json\/wp\/v2\/media?parent=4613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}